{"id":5291,"date":"2020-10-08T18:05:00","date_gmt":"2020-10-08T18:05:00","guid":{"rendered":"https:\/\/testavalems.opointzero.ch\/covid-en-ems-serie-radio\/"},"modified":"2021-09-02T18:20:01","modified_gmt":"2021-09-02T18:20:01","slug":"covid-en-ems-serie-radio","status":"publish","type":"post","link":"https:\/\/avalems.ch\/de\/covid-en-ems-serie-radio\/","title":{"rendered":"COVID en EMS: S\u00e9rie radio"},"content":{"rendered":"\n<p>L&#8217;\u00e9mission VACARME de RTS La Premi\u00e8re \u00e9tait consacr\u00e9e toute la semaine au COVID en EMS. Les t\u00e9moignages ont \u00e9t\u00e9 enregistr\u00e9s dans des EMS valaisans.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<h4>Covid en EMS 1\/5 &#8211; Le blues des familles<\/h4>\n<p>Juin 2020: c\u02b9est l\u02b9heure pour les familles de retrouver leurs proches apr\u00e8s trois mois de contact \u00e0 distance. \u00c0 la r\u00e9sidence m\u00e9dicalis\u00e9e du Glarier, au centre de Sion, les mesures sont strictes et les visites encadr\u00e9es. Directrice, m\u00e9decin et infirmi\u00e8re-cheffe organisent la premi\u00e8re r\u00e9union post-confinement. Les familles et les pensionnaires demandent des explications.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/tp.srgssr.ch\/p\/srf\/embed?urn=urn:rts:audio:11618589&amp;start=\" name=\"Covid en EMS 1\/5 - Le blues des familles\" width=\"392\" height=\"58\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><\/p>\n<h4>Covid en EMS 2\/5 &#8211; &#8222;Chic, on va mourir ensemble&#8220;<\/h4>\n<p>Quand Roselma et son mari Basile ont \u00e9t\u00e9 infect\u00e9s par le coronavirus, le couple s\u02b9est r\u00e9joui \u00e0 l\u02b9id\u00e9e de mourir ensemble. Mais seul Basile est d\u00e9c\u00e9d\u00e9 et Roselma reste l\u00e0, \u00e0 raconter. \u00c0 l\u02b9EMS Haut de Cry \u00e0 V\u00e9troz en Valais, 14 r\u00e9sident\u00b7e\u00b7s sont d\u00e9c\u00e9d\u00e9\u00b7e\u00b7s. Anne Carroz, la m\u00e9decin r\u00e9f\u00e9rente et Marie Jo Bugnon, l\u02b9infirmi\u00e8re de l\u02b9\u00e9tage reviennent sur ce printemps hors du temps o\u00f9 le virus a traumatis\u00e9 tout l\u02b9\u00e9tablissement.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/tp.srgssr.ch\/p\/srf\/embed?urn=urn:rts:audio:11621998&amp;start=\" name=\"Covid en EMS 2\/5 - &quot;Chic, on va mourir ensemble&quot;\" width=\"392\" height=\"58\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><\/p>\n<h4>Covid en EMS 3\/5 &#8211; Libert\u00e9 contr\u00f4l\u00e9e<\/h4>\n<p>\u00c0 la r\u00e9sidence m\u00e9dicalis\u00e9e du Glarier \u00e0 Sion, les journ\u00e9es d\u00e9marrent par la lecture de la presse, suivie de la communion, parfois. Les repas et les diverses activit\u00e9s viennent ensuite rythmer cette vie au ralenti. Comment le Covid a-t-il chamboul\u00e9 la vie des pensionnaires de l\u02b9\u00c9tablissement? Entre adaptation, sagesse, r\u00e9volte ou d\u00e9prime, les r\u00e9sident\u00b7e\u00b7s racontent leur vision de la libert\u00e9.&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/tp.srgssr.ch\/p\/srf\/embed?urn=urn:rts:audio:11624529&amp;start=\" name=\"Covid en EMS 3\/5 - Libert\u00e9 contr\u00f4l\u00e9e\" width=\"392\" height=\"58\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><\/p>\n<h4>Covid en EMS 4\/5 &#8211; Soignant\u00b7e\u00b7s sous pression<\/h4>\n<p>Emmanuel, Philippa, Chrystel ou Rica sont les soignant\u00b7e\u00b7s de la r\u00e9sidence m\u00e9dicalis\u00e9e du Glarier \u00e0 Sion. Depuis des mois, toute l\u02b9\u00e9quipe se d\u00e9sinfecte les mains sans arr\u00eat, v\u00e9rifie les temp\u00e9ratures en permanence, limite ses interactions de peur de ramener le virus dans l\u02b9institution. Une pression nouvelle qui s\u02b9ajoute \u00e0 un rythme de travail soutenu, pour une reconnaissance qui se fait attendre.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/tp.srgssr.ch\/p\/srf\/embed?urn=urn:rts:audio:11626784&amp;start=\" name=\"Covid en EMS 4\/5 - Soignant\u00b7e\u00b7s sous pression\" width=\"392\" height=\"58\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9mission VACARME de RTS La Premi\u00e8re \u00e9tait consacr\u00e9e toute la semaine au COVID en EMS. Les t\u00e9moignages ont \u00e9t\u00e9 enregistr\u00e9s dans des EMS valaisans.<\/p>\n","protected":false},"author":152,"featured_media":5289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"coauthors":[],"class_list":["post-5291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"publishpress_future_action":{"enabled":false,"date":"2026-06-13 16:43:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/5291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/users\/152"}],"replies":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/comments?post=5291"}],"version-history":[{"count":1,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/5291\/revisions"}],"predecessor-version":[{"id":5292,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/5291\/revisions\/5292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media\/5289"}],"wp:attachment":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media?parent=5291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/categories?post=5291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/tags?post=5291"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/coauthors?post=5291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}