{"id":37551,"date":"2025-12-22T16:12:30","date_gmt":"2025-12-22T15:12:30","guid":{"rendered":"https:\/\/avalems.ch\/?p=37551"},"modified":"2025-12-22T16:12:32","modified_gmt":"2025-12-22T15:12:32","slug":"assistent-gesundheit-und-soziales-eba-2","status":"publish","type":"post","link":"https:\/\/avalems.ch\/de\/assistent-gesundheit-und-soziales-eba-2\/","title":{"rendered":"Assistent Gesundheit und Soziales (EBA)"},"content":{"rendered":"\n<p>Assistentinnen \/ Assistenten Gesundheit und Soziales beteiligen sich an der Organisation der allt\u00e4glichen T\u00e4tigkeiten, um das physische, psychische und soziale Wohlergehen von Menschen jeden Alters zu gew\u00e4hrleisten. Unter Anleitung von Pflege- und Betreuungspersonal f\u00fchren sie Grundpflege (Hygiene, Ern\u00e4hrung) und Unterhaltsarbeiten durch. Sie entwickeln und f\u00f6rdern zwischenmenschliche Beziehungen.<\/p>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.ortrassvs.ch\/de\/ich-suche-eine-ausbildung\/berufsausbildung\/assistent-gesundheit-und-soziales-eba-345\/\" target=\"_blank\" rel=\"noopener\">Termine, Preise und weitere Informationen<\/a><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assistentinnen \/ Assistenten Gesundheit und Soziales beteiligen sich an der Organisation der allt\u00e4glichen T\u00e4tigkeiten, um das physische, psychische und soziale Wohlergehen von Menschen jeden Alters zu gew\u00e4hrleisten. Unter Anleitung von [&hellip;]<\/p>\n","protected":false},"author":349,"featured_media":15514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[434,444],"tags":[611],"coauthors":[411],"class_list":["post-37551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weiterbildung","category-weiterbildung-von-partnern","tag-kpz-pflegehelfer"],"publishpress_future_action":{"enabled":false,"date":"2026-06-14 01:41:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/37551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/comments?post=37551"}],"version-history":[{"count":1,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/37551\/revisions"}],"predecessor-version":[{"id":37553,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/37551\/revisions\/37553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media\/15514"}],"wp:attachment":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media?parent=37551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/categories?post=37551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/tags?post=37551"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/coauthors?post=37551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}