{"id":2586,"date":"2021-04-08T20:47:00","date_gmt":"2021-04-08T20:47:00","guid":{"rendered":"https:\/\/testavalems.opointzero.ch\/les-ems-suisses-se-sont-sentis-abandonnes-par-les-autorites-en-valais-cest-tout-le-contraire\/"},"modified":"2021-08-11T20:48:44","modified_gmt":"2021-08-11T20:48:44","slug":"les-ems-suisses-se-sont-sentis-abandonnes-par-les-autorites-en-valais-cest-tout-le-contraire","status":"publish","type":"post","link":"https:\/\/avalems.ch\/de\/les-ems-suisses-se-sont-sentis-abandonnes-par-les-autorites-en-valais-cest-tout-le-contraire\/","title":{"rendered":"Les EMS suisses se sont sentis abandonn\u00e9s par les autorit\u00e9s. En Valais, c&#8217;est tout le contraire"},"content":{"rendered":"\n<p>&#8222;Abandonn\u00e9s par les autorit\u00e9s&#8220; c&#8217;est l&#8217;un des sentiments qui pr\u00e9dominent dans les \u00e9tablissements m\u00e9dicaux-sociaux (EMS) helv\u00e9tiques. Or, ces conclusions se basent sur les r\u00e9ponses de responsables d\u2019\u00e9tablissements majoritairement situ\u00e9s en Suisse al\u00e9manique. Ce qui peut expliquer qu\u2019en Valais, la position est diam\u00e9tralement oppos\u00e9e.<\/p>\n\n\n\n<p>On est loin de l\u00e0 : en Valais, le canton a vraiment jou\u00e9 un r\u00f4le primordial\u2026 en particulier le service de la sant\u00e9 public mais aussi celui de la protection civile et nous avons pu compter sur tous nos partenaires, c\u2019est-\u00e0-dire les h\u00f4pitaux, les m\u00e9decins, les pharmaciens\u2026 &#8222;, rel\u00e8ve Arnaud Schaller, directeur de l&#8217;AVALEMS.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><a target=\"_blank\" href=\"https:\/\/www.rhonefm.ch\/actualites\/les-ems-suisses-se-sont-sentis-abandonnes-par-les-autorites-en-valais-cest-tout-le-contraire\" rel=\"noreferrer noopener\">L&#8217;article complet sur le site de Rhone FM<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Abandonn\u00e9s par les autorit\u00e9s&#8220; c&#8217;est l&#8217;un des sentiments qui pr\u00e9dominent dans les \u00e9tablissements m\u00e9dicaux-sociaux (EMS) helv\u00e9tiques. Or, ces conclusions se basent sur les r\u00e9ponses de responsables d\u2019\u00e9tablissements majoritairement situ\u00e9s en Suisse al\u00e9manique. Ce qui peut expliquer qu\u2019en Valais, la position est diam\u00e9tralement oppos\u00e9e.<\/p>\n","protected":false},"author":152,"featured_media":2467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"coauthors":[],"class_list":["post-2586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revue-de-presse-de"],"publishpress_future_action":{"enabled":false,"date":"2026-06-14 00:43:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/2586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/users\/152"}],"replies":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/comments?post=2586"}],"version-history":[{"count":1,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/2586\/revisions"}],"predecessor-version":[{"id":2587,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/posts\/2586\/revisions\/2587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media?parent=2586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/categories?post=2586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/tags?post=2586"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/coauthors?post=2586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}