{"id":8275,"date":"2021-07-27T18:41:07","date_gmt":"2021-07-27T16:41:07","guid":{"rendered":"https:\/\/testavalems.opointzero.ch\/ems\/ems-gravelone\/"},"modified":"2025-01-23T09:28:51","modified_gmt":"2025-01-23T08:28:51","slug":"ems-gravelone","status":"publish","type":"ems","link":"https:\/\/avalems.ch\/de\/ems\/ems-gravelone\/","title":{"rendered":"EMS &#8222;GRAVELONE&#8220;"},"content":{"rendered":"","protected":false},"author":305,"featured_media":0,"menu_order":0,"template":"","regions":[59],"benefits":[42],"coauthors":[342],"class_list":["post-8275","ems","type-ems","status-publish","hentry","regions-sitten","benefits-sejour-long-de"],"publishpress_future_action":{"enabled":false,"date":"2026-06-13 21:56:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"benefits","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/ems\/8275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/ems"}],"about":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/types\/ems"}],"author":[{"embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/users\/305"}],"version-history":[{"count":1,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/ems\/8275\/revisions"}],"predecessor-version":[{"id":28967,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/ems\/8275\/revisions\/28967"}],"wp:attachment":[{"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/media?parent=8275"}],"wp:term":[{"taxonomy":"regions","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/regions?post=8275"},{"taxonomy":"benefits","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/benefits?post=8275"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avalems.ch\/de\/wp-json\/wp\/v2\/coauthors?post=8275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}